{"id":24691,"date":"2024-05-14T08:50:10","date_gmt":"2024-05-14T08:50:10","guid":{"rendered":"https:\/\/hdcmfg.com\/?p=24691"},"modified":"2026-03-10T08:46:10","modified_gmt":"2026-03-10T08:46:10","slug":"guide-dachat-des-charnieres-pour-piano-2","status":"publish","type":"post","link":"https:\/\/hdcmfg.com\/fr\/resources\/blog\/piano-hinge-buying-guide-2\/","title":{"rendered":"Guide d\u2019achat de charni\u00e8res pour piano"},"content":{"rendered":"<h2>Informations de base sur la charni\u00e8re de piano\u00a0:<\/h2>\n<h3>Qu&#039;est-ce qu&#039;une charni\u00e8re de piano ?<\/h3>\n<p>Une charni\u00e8re \u00e0 piano, \u00e9galement appel\u00e9e charni\u00e8re continue, se pr\u00e9sente comme une charni\u00e8re allong\u00e9e et mince dot\u00e9e d&#039;un assemblage de feuilles imbriqu\u00e9es. Il s&#039;\u00e9tend sur toute la longueur du couvercle\/de la porte. De cette fa\u00e7on, la quantit\u00e9 de charge est r\u00e9partie uniform\u00e9ment dans toute la charni\u00e8re, ce qui lui permet de supporter des charges plus \u00e9lev\u00e9es. La nomenclature \u00ab\u00a0charni\u00e8re de piano\u00a0\u00bb d\u00e9rive de son d\u00e9ploiement fr\u00e9quent dans les limites des ensembles de couvercles de piano.<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2024\/01\/Custom-Piano-Hinges-6.webp\" alt=\"charni\u00e8res piano sur mesure 6\" width=\"1200\" height=\"800\" \/><\/p>\n<h3>Les charni\u00e8res continues sont-elles solides\u00a0?<\/h3>\n<p>Oui. Les charni\u00e8res continues sont extr\u00eamement solides et peuvent supporter une charge plusieurs fois sup\u00e9rieure \u00e0 leur poids. De plus, les charni\u00e8res continues sont disponibles en diff\u00e9rentes tailles, formes, \u00e9paisseurs, diam\u00e8tres d&#039;axe, longueurs d&#039;articulation, etc. vous devez choisir la meilleure combinaison pour vos exigences de charge.<\/p>\n<h3>Comparez les charni\u00e8res piano aux charni\u00e8res ordinaires<\/h3>\n<p>C\u2019est principalement gr\u00e2ce \u00e0 la conception de la charni\u00e8re piano qu\u2019elle peut supporter plus de charge pour un rapport de poids donn\u00e9. Les charni\u00e8res piano fonctionnent en continu sur toute la longueur du couvercle\/de la porte. Ainsi, la charge sur la charni\u00e8re est r\u00e9partie uniform\u00e9ment. Ainsi, les charni\u00e8res continues peuvent supporter des charges plus importantes que les charni\u00e8res normales.<\/p>\n<h3>Poids qu&#039;une charni\u00e8re continue peut supporter<\/h3>\n<p>Cela d\u00e9pend du mat\u00e9riau et de la technologie de fabrication de la charni\u00e8re. G\u00e9n\u00e9ralement, un 1&quot;<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/stainless-steel-piano-hinges-3-1.jpg\" alt=\"charni\u00e8res piano en acier inoxydable 3\" width=\"800\" height=\"533\" \/><\/p>\n<p>Une charni\u00e8re de piano \u00e9paisse de 24 po peut supporter 60 lb. de charge. Alors qu&#039;une charni\u00e8re continue de 2 pouces peut supporter une charge allant jusqu&#039;\u00e0 2,5 lb par pouce pour la longueur de la charni\u00e8re. Cependant, tout en utilisant diff\u00e9rents mat\u00e9riaux, ce poids peut augmenter consid\u00e9rablement jusqu&#039;\u00e0 900 livres. par heure.<\/p>\n<h3>O\u00f9 peut-on appliquer une charni\u00e8re de piano ?<\/h3>\n<p>Les charni\u00e8res piano pr\u00e9sentent un degr\u00e9 extraordinaire de polyvalence, ce qui les rend inestimables dans une myriade d&#039;applications diverses, qui englobent, sans s&#039;y limiter, les \u00e9l\u00e9ments suivants\u00a0:<\/p>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Armoires<\/strong><\/li>\n<li><strong>Bateaux et Marine<\/strong>.<\/li>\n<li><strong>A\u00e9rospatial<\/strong><\/li>\n<li><strong>\u00c9quipement industriel<\/strong><\/li>\n<li><strong>Meubles<\/strong><\/li>\n<\/ul>\n<p>Les charni\u00e8res piano sont utilis\u00e9es dans de multiples applications allant de la fabrication de meubles aux couvercles. D&#039;autres applications des charni\u00e8res de piano comprennent le montage de portes, de rampes, de bo\u00eetes de rangement, de portes d&#039;armoires et de bureaux rabattables, etc. En raison de leur capacit\u00e9 de charge plus \u00e9lev\u00e9e, les charni\u00e8res de piano sont id\u00e9ales pour les applications o\u00f9 il y a une charge plus \u00e9lev\u00e9e mais moins d&#039;espace pour travailler avec.<\/p>\n<h3>Types de charni\u00e8res de piano<\/h3>\n<p>Il existe de nombreuses vari\u00e9t\u00e9s de charni\u00e8res de piano, et voici quelques types couramment utilis\u00e9s\u00a0:<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/stainless-steel-piano-hinges-2.jpg\" alt=\"charni\u00e8res piano en acier inoxydable 2\" width=\"800\" height=\"533\" \/><\/p>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Charni\u00e8res de piano \u00e0 friction<\/strong><\/li>\n<li><strong>Charni\u00e8res \u00e0 piano \u00e0 engrenages<\/strong><\/li>\n<li><strong>Charni\u00e8res de piano interfeuillets<\/strong><\/li>\n<li><strong>Charni\u00e8res \u00e0 piano \u00e0 broches et \u00e0 barillet<\/strong><\/li>\n<li><strong>Charni\u00e8res piano demi-surface<\/strong><\/li>\n<li><strong>Charni\u00e8res piano pleine surface<\/strong><\/li>\n<li><strong>Charni\u00e8res de piano demi-mortaise<\/strong><\/li>\n<\/ul>\n<h3>Mat\u00e9riaux \u00e0 partir desquels les charni\u00e8res de piano sont fabriqu\u00e9es<\/h3>\n<p>Les charni\u00e8res piano peuvent \u00eatre fabriqu\u00e9es \u00e0 partir de divers mat\u00e9riaux, notamment\u00a0:<\/p>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Acier:<\/strong>solide et durable, adapt\u00e9 aux applications intensives.<\/li>\n<li><strong><a href=\"https:\/\/hdcmfg.com\/fr\/charnieres-piano-en-acier-inoxydable-3\/\">Acier inoxydable<\/a>:<\/strong>offre une excellente r\u00e9sistance \u00e0 la corrosion, adapt\u00e9e aux applications ext\u00e9rieures et marines.<\/li>\n<li><strong><a href=\"https:\/\/hdcmfg.com\/fr\/charnieres-de-piano-en-aluminium\/\">Aluminium<\/a>:<\/strong>l\u00e9ger et r\u00e9sistant \u00e0 la corrosion, souvent utilis\u00e9 dans les industries a\u00e9rospatiale et automobile.<\/li>\n<\/ul>\n<h3>Choisissez la bonne charni\u00e8re de piano<\/h3>\n<p>Lors de la s\u00e9lection d&#039;une charni\u00e8re de piano, vous devez examiner quelques aspects de la charni\u00e8re pour commander la charni\u00e8re appropri\u00e9e.<\/p>\n<p>Tout d&#039;abord, v\u00e9rifiez le mat\u00e9riau de la charni\u00e8re. Ce mat\u00e9riau doit \u00eatre capable de supporter la charge de votre porte\/couvercle. Choisissez-le \u00e9galement en fonction de l&#039;utilisation pr\u00e9vue.<\/p>\n<p>Deuxi\u00e8mement, vous devez v\u00e9rifier la libert\u00e9 de rotation des charni\u00e8res continues qui convient \u00e0 votre application.<\/p>\n<p>Ensuite, vous devez voir l&#039;option d&#039;installation dans la charni\u00e8re, si vous avez besoin de la charni\u00e8re avec des trous ou si vous devez souder la charni\u00e8re.<\/p>\n<p>Vous devez \u00e9galement v\u00e9rifier le diam\u00e8tre de la broche et l&#039;adapter \u00e0 vos besoins.<\/p>\n<p>Et enfin, vous devez voir si la finition de la charni\u00e8re du piano est correcte ou non.<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/stainless-steel-piano-hinges-1-1.jpg\" alt=\"charni\u00e8res piano en acier inoxydable 1\" width=\"800\" height=\"533\" \/><\/p>\n<p>Le choix de la bonne charni\u00e8re piano d\u00e9pend de plusieurs facteurs :<\/p>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Mat\u00e9riel: <\/strong>Tenez compte des conditions environnementales et des exigences de charge pour choisir le mat\u00e9riau appropri\u00e9.<\/li>\n<li><strong>Taille: <\/strong>Mesurez la longueur et la largeur des surfaces que vous souhaitez connecter et s\u00e9lectionnez une charni\u00e8re qui correspond \u00e0 ces dimensions.<\/li>\n<li><strong>Capacit\u00e9 de chargement: <\/strong>Diff\u00e9rentes charni\u00e8res de piano ont des capacit\u00e9s de charge variables. Assurez-vous que votre charni\u00e8re peut supporter le poids de votre application.<\/li>\n<li><strong>Finition: <\/strong>Les charni\u00e8res piano sont disponibles en diff\u00e9rentes finitions, alors choisissez-en une qui compl\u00e8te l&#039;esth\u00e9tique de votre projet.<\/li>\n<li><strong>Installation: <\/strong>Consid\u00e9rez comment la charni\u00e8re sera install\u00e9e. Certains sont dot\u00e9s de trous pr\u00e9-perc\u00e9s pour une installation plus facile.<\/li>\n<\/ul>\n<h3>Puis-je installer les charni\u00e8res de piano moi-m\u00eame\u00a0?<\/h3>\n<p>Oui, vous pouvez installer vous-m\u00eame des charni\u00e8res piano avec les bons outils et une bonne compr\u00e9hension du proc\u00e9d\u00e9. Les charni\u00e8res piano peuvent \u00eatre fix\u00e9es \u00e0 votre rampe, porte ou couvercle de piano par fixation ou par soudage.<\/p>\n<p>Cependant, la plupart des charni\u00e8res de piano ont des trous qui peuvent \u00eatre utilis\u00e9s pour adapter les charni\u00e8res \u00e0 la porte\/au couvercle, etc. Cependant, vous devrez prendre les mesures appropri\u00e9es de la porte\/du couvercle avant d&#039;installer les charni\u00e8res de piano.<\/p>\n<p>L&#039;installation d&#039;une charni\u00e8re piano peut varier selon le projet et les mat\u00e9riaux utilis\u00e9s. Consultez toujours les instructions du fabricant et adaptez le processus \u00e0 votre situation.<\/p>\n<p>Avec des mesures minutieuses et une attention aux d\u00e9tails, vous devriez \u00eatre en mesure d&#039;installer vous-m\u00eame une charni\u00e8re de piano avec succ\u00e8s.<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/marine-piano-hinges-1.jpg\" alt=\"charni\u00e8res de piano marin 1\" width=\"800\" height=\"533\" \/><\/p>\n<h3>Puis-je obtenir des charni\u00e8res de piano personnalis\u00e9es ?<\/h3>\n<p>Oui, les charni\u00e8res piano sont disponibles en diff\u00e9rentes tailles et longueurs. Cependant, il peut arriver que vous ne trouviez pas la longueur souhait\u00e9e. Dans ce cas, vous pouvez personnaliser les charni\u00e8res piano surdimensionn\u00e9es selon vos besoins.<\/p>\n<p>De nombreux fabricants, dont HDC, proposent <a href=\"https:\/\/hdcmfg.com\/fr\/produits-sur-mesure\/charniere-a-piano\/\"><strong>charni\u00e8res de piano personnalis\u00e9es<\/strong><\/a>Ces charni\u00e8res peuvent \u00eatre adapt\u00e9es \u00e0 vos dimensions, mat\u00e9riaux et finitions. Elles sont id\u00e9ales lorsque les dimensions et options standard ne r\u00e9pondent pas aux besoins de votre projet.<\/p>\n<h2>Guide d&#039;achat \u00e9tape par \u00e9tape<\/h2>\n<h3>Choisissez les mat\u00e9riaux appropri\u00e9s<\/h3>\n<p>Les charni\u00e8res piano sont disponibles dans diff\u00e9rents mat\u00e9riaux, chacun pr\u00e9sentant ses propres avantages et inconv\u00e9nients. Les mat\u00e9riaux les plus courants comprennent :<\/p>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Acier:<\/strong>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Avantages :<\/strong>solide, durable et peut supporter de lourdes charges.<\/li>\n<li><strong>D\u00e9savantages:<\/strong>Ils peuvent rouiller s\u2019ils ne sont pas correctement recouverts ou s\u2019ils ne sont pas fabriqu\u00e9s en acier inoxydable.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Acier inoxydable:<\/strong>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Avantages :<\/strong>r\u00e9sistant \u00e0 la corrosion, adapt\u00e9 aux applications ext\u00e9rieures et marines.<\/li>\n<li><strong>D\u00e9savantages:<\/strong>plus cher que les autres mat\u00e9riaux.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Aluminium:<\/strong>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Avantages :<\/strong>l\u00e9ger et r\u00e9sistant \u00e0 la corrosion.<\/li>\n<li><strong>D\u00e9savantages:<\/strong>La r\u00e9sistance est plus faible que celle de l&#039;acier et peut ne pas convenir aux charges lourdes.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Choisissez le mat\u00e9riau qui r\u00e9pond le mieux aux exigences de votre projet, en tenant compte de facteurs tels que la capacit\u00e9 de charge, l&#039;environnement et l&#039;apparence.<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/marine-piano-hinges-3.jpg\" alt=\"charni\u00e8res de piano marin 3\" width=\"800\" height=\"533\" \/><\/p>\n<h3>D\u00e9terminer la taille et la longueur<\/h3>\n<p>Les charni\u00e8res piano sont disponibles en diff\u00e9rentes longueurs et largeurs. Mesurez les dimensions de la zone o\u00f9 vous pr\u00e9voyez d&#039;installer la charni\u00e8re pour d\u00e9terminer la taille appropri\u00e9e. Assurez-vous que la longueur de la charni\u00e8re couvre ad\u00e9quatement tout le bord o\u00f9 elle sera mont\u00e9e.<\/p>\n<h3>D\u00e9terminer l&#039;\u00e9paisseur appropri\u00e9e<\/h3>\n<p>Tenez compte de l&#039;\u00e9paisseur du mat\u00e9riau de la charni\u00e8re. Les charni\u00e8res plus \u00e9paisses ont tendance \u00e0 \u00eatre plus durables et capables de supporter des charges plus lourdes, mais elles peuvent aussi \u00eatre plus volumineuses. Choisissez une \u00e9paisseur qui \u00e9quilibre vos exigences de charge et vos limites d&#039;espace.<\/p>\n<h3>S\u00e9lectionnez une finition qui convient aux exigences de votre projet<\/h3>\n<p>La finition d\u2019une charni\u00e8re piano affecte son apparence et sa r\u00e9sistance \u00e0 la corrosion. Les finitions courantes comprennent\u00a0:<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/aluminum-piano-hinges-1.jpg\" alt=\"charni\u00e8res piano en aluminium 1\" width=\"800\" height=\"533\" \/><\/p>\n<ul style=\"list-style-type: disc; color: black;\">\n<li><strong>Plaine<\/strong>: Acier ou m\u00e9tal brut.<\/li>\n<li><strong>Zingu\u00e9<\/strong>: Fournit une certaine r\u00e9sistance \u00e0 la corrosion.<\/li>\n<li><strong>Brillant<\/strong>: Offre une surface attrayante et r\u00e9fl\u00e9chissante.<\/li>\n<li><strong>Noir ou rev\u00eatement en poudre<\/strong>: Offre une r\u00e9sistance \u00e0 la corrosion et un aspect mat.<\/li>\n<\/ul>\n<p>S\u00e9lectionnez la finition qui convient \u00e0 vos pr\u00e9f\u00e9rences esth\u00e9tiques et \u00e0 l&#039;environnement pr\u00e9vu de la charni\u00e8re.<\/p>\n<h3>Sp\u00e9cifiez vos exigences de charge<\/h3>\n<p>Tenez compte des exigences de poids et de capacit\u00e9 de charge de votre application. Assurez-vous que la charni\u00e8re s\u00e9lectionn\u00e9e peut supporter la charge attendue sans se plier ni \u00e9chouer. Les fabricants sp\u00e9cifient souvent des capacit\u00e9s de charge pour leurs charni\u00e8res, alors faites attention \u00e0 ces valeurs.<\/p>\n<h3>Pensez \u00e0 la durabilit\u00e9<\/h3>\n<p>Pour des performances durables, recherchez des charni\u00e8res piano dot\u00e9es de caract\u00e9ristiques telles que des articulations ou des roulements renforc\u00e9s. Ces am\u00e9liorations r\u00e9duisent l\u2019usure, ce qui prolonge la dur\u00e9e de vie de la charni\u00e8re.<\/p>\n<h3>D\u00e9terminer la m\u00e9thode d&#039;installation<\/h3>\n<p>V\u00e9rifiez si la charni\u00e8re est livr\u00e9e avec des trous ou des fentes pr\u00e9-perc\u00e9s pour une installation facile. Certaines charni\u00e8res peuvent n\u00e9cessiter une soudure, tandis que d&#039;autres peuvent \u00eatre fix\u00e9es avec des vis ou des rivets. Choisissez une charni\u00e8re qui correspond \u00e0 votre m\u00e9thode d&#039;installation et \u00e0 votre niveau de comp\u00e9tence.<img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/marine-piano-hinges-2.jpg\" alt=\"installation de charni\u00e8res de piano\" width=\"800\" height=\"533\" \/><\/p>\n<h3>Choisissez dans votre fourchette budg\u00e9taire<\/h3>\n<p>Le prix d\u2019une charni\u00e8re piano peut varier consid\u00e9rablement en fonction des diff\u00e9rences de mat\u00e9riaux, de dimensions et de types. rester attentif \u00e0 vos contraintes budg\u00e9taires tout en accordant une importance primordiale aux facettes de la qualit\u00e9 et de la durabilit\u00e9. Cette approche strat\u00e9gique garantit l\u2019att\u00e9nuation des r\u00e9quisitions futures potentielles.<\/p>\n<h3>Quantit\u00e9<\/h3>\n<p>Assurez-vous d&#039;acheter la bonne quantit\u00e9 de charni\u00e8res pour votre projet. C&#039;est toujours une bonne id\u00e9e d&#039;acheter quelques extras en cas d&#039;erreurs ou de futurs remplacements.<\/p>\n<h2>Conclusion<\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/hdcmfg.com\/wp-content\/uploads\/2023\/10\/steel-piano-hinges-3.jpg\" alt=\"charni\u00e8res piano en acier 3\" width=\"800\" height=\"533\" \/><br \/>\nEn suivant ce guide d&#039;achat de charni\u00e8res pour piano, vous pouvez choisir en toute confiance la charni\u00e8re adapt\u00e9e \u00e0 votre projet, garantissant un fonctionnement fluide et des performances durables.<\/p>\n<p>Pour toute demande de charni\u00e8re de piano sur mesure, veuillez remplir le formulaire sur notre site web et nous faire part de vos besoins, notamment en termes de dimensions, mat\u00e9riaux, finitions, etc. Notre \u00e9quipe commerciale professionnelle vous contactera rapidement. Nous v\u00e9rifierons vos besoins et vous accompagnerons tout au long du processus de fabrication de votre charni\u00e8re de piano sur mesure.<\/p>\n<p>Nous proposons un service d&#039;\u00e9chantillons gratuits. Vous pouvez en demander pour vous assurer que la qualit\u00e9 r\u00e9pond \u00e0 vos exigences. Si vous poss\u00e9dez d\u00e9j\u00e0 des charni\u00e8res piano pr\u00e9fabriqu\u00e9es et souhaitez les personnaliser en grande quantit\u00e9, envoyez-nous vos \u00e9chantillons. Cela acc\u00e9l\u00e9rera consid\u00e9rablement le processus de personnalisation. Avec notre aide, vous obtiendrez la charni\u00e8re piano la mieux adapt\u00e9e aux exigences sp\u00e9cifiques de votre projet.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les charni\u00e8res piano, \u00e9galement connues sous le nom de charni\u00e8res continues, sont des composants essentiels utilis\u00e9s pour r\u00e9partir uniform\u00e9ment le poids sur la longueur des portes, des couvercles et de diverses applications. Ce guide explore les types, les mat\u00e9riaux et les applications des charni\u00e8res piano, vous aidant \u00e0 choisir la bonne charni\u00e8re en fonction de vos besoins sp\u00e9cifiques.<\/p>","protected":false},"author":4,"featured_media":16348,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Everything You Need to Know About Selecting the Perfect Continuous Hinge","_seopress_titles_desc":"This guide explores the types, materials, and applications of piano hinges, helping you choose the right hinge based on your specific needs. With the right hinge, you ensure durability and functionality for your project.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"disabled","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[101],"tags":[343,83,99,82],"class_list":["post-24691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-acf-temp","tag-blog","tag-blog-hinges-and-hardware","tag-resources"],"acf":[],"_links":{"self":[{"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/posts\/24691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/comments?post=24691"}],"version-history":[{"count":19,"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/posts\/24691\/revisions"}],"predecessor-version":[{"id":105961,"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/posts\/24691\/revisions\/105961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/media\/16348"}],"wp:attachment":[{"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/media?parent=24691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/categories?post=24691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hdcmfg.com\/fr\/wp-json\/wp\/v2\/tags?post=24691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}